{"id":1013,"date":"2020-05-21T22:06:43","date_gmt":"2020-05-21T22:06:43","guid":{"rendered":"https:\/\/tribunavm.com.ar\/?p=1013"},"modified":"2020-05-21T22:25:08","modified_gmt":"2020-05-21T22:25:08","slug":"entre-gallos-y-medianoche-schiaretti-recorta-jubilaciones-provinciales","status":"publish","type":"post","link":"https:\/\/tribunavm.com.ar\/index.php\/2020\/05\/21\/entre-gallos-y-medianoche-schiaretti-recorta-jubilaciones-provinciales\/","title":{"rendered":"Entre \u201cgallos y medianoche\u201d Schiaretti recorta jubilaciones provinciales"},"content":{"rendered":"<div class=\"row clearfix\">\n<div class=\"col-md-8\">\n<div class=\"intro-text\">\n<p><i><span style=\"font-weight: 400;\">Rotundo rechazo al proyecto de Ley impulsado por el oficialismo provincial que busca reducir los haberes jubilatorios. Centrales de trabajadores y gremios de toda la provincia denunciaron la medida.<\/span><\/i><\/p>\n<\/div>\n<p><span class=\"dropcap \" style=\"background-color: #ffffff; color: #dd9933; border-color: #ffffff;\">C<\/span>on 46 votos a favor, 12 en contra, 3 abstenciones, y 9 ausentes, el Gobierno de C\u00f3rdoba impuls\u00f3 y aprob\u00f3, en la legislatura provincial un proyecto denominado \u201cProyecto de ley para fortalecer la solidaridad y sostenibilidad de la Caja de Jubilaciones\u201d.<\/p>\n<p><span style=\"font-weight: 400;\">El texto propone el objetivo de disminuir el d\u00e9ficit estructural de la Caja de Jubilaciones Provincial (108.000 jubilaciones y pensiones) que el Gobierno estima que rondar\u00e1 los 35.500 millones de pesos para este a\u00f1o. Adem\u00e1s, el proyecto incluir\u00eda una modificaci\u00f3n en la edad jubilatoria para los magistrados judiciales, llev\u00e1ndola de 60 a 65 a\u00f1os y reduciendo el porcentaje de pensiones, fijando el monto de la pensi\u00f3n como el equivalente al 70% de la jubilaci\u00f3n del causante, en lugar del 75% actual.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El repudio al ajuste por parte de las organizaciones sindicales fue total: En Villa Mar\u00eda se realiz\u00f3 hoy, en la sede de UEPC (Uni\u00f3n de Educadores de la Provincia), una conferencia de prensa donde dirigentes de la CGT y la CTA-A locales rechazaron de forma rotunda los sucesos de ayer, adem\u00e1s de reclamar por conflictos que vienen atravesando los trabajadores como la situaci\u00f3n de los despidos en F\u00e1brica Militar, el retraso de los pagos salariales de los choferes de transporte urbano e interurbano, monotributistas, entre otros.<\/span><\/p>\n<blockquote class=\"pullquote align-center\"><p><span style=\"font-weight: 400;\">\u201cEsto claramente agranda la desigualdad social en plena pandemia. Le pedimos al Gobernador que le meta la mano a la renta financiera , a los cerealeros, a los terratenientes, pero no a la clase trabajadora, a los jubilados y las jubiladas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gustavo Vilches, Secretario de CTA Aut\u00f3noma Villa Mar\u00eda.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Edgardo Garmendia, Secretario General de la CGT Regional Villa Mar\u00eda dijo: \u201cNo podemos nivelar para abajo. Nosotros entendemos que estamos ante una situaci\u00f3n de crisis, pero sin consulta ni consenso, no podemos hacer otra cosa que rechazar la medida con nuestra total energ\u00eda. Es una situaci\u00f3n aberrante\u201d. Adem\u00e1s, denunci\u00f3 las consecuencias que sufren varios sectores del movimiento obrero: \u201ctenemos compa\u00f1eros que est\u00e1n padeciendo hambre. hoy no se trata de una cuesti\u00f3n pol\u00edtica, es una cuesti\u00f3n humanitaria\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, Pablo Bertoglio, Secretario General de La Bancaria Villa Mar\u00eda, denunci\u00f3 fervientemente a los legisladores que votaron esta Ley: \u201cson unos traidores, vengan del palo que vengan, por que se est\u00e1n riendo de los trabajadores\u201d. Tambien record\u00f3 que la oposici\u00f3n que ayer se opon\u00eda \u201cfue la misma que vot\u00f3 a favor de la reforma jubilatoria que le quit\u00f3 el derecho a todos los jubilados\u201d, en referencia a la reforma previsional en 2017.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al finalizar la conferencia, leyeron un documento que elaboraron conjuntamente denunciando que la medida impulsada por el Gobernador de C\u00f3rdoba es un atropello a los trabajadores, aunque no es el \u00fanico que est\u00e1 sufriendo en este contexto de pandemia,\u201dsean estos trabajadores p\u00fablicos provinciales, nacionales o privados\u201d. <\/span><\/p>\n<figure id=\"attachment_1022\" aria-describedby=\"caption-attachment-1022\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1022\" src=\"https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/DSC_0024-1024x1000.jpg\" alt=\"\" width=\"1024\" height=\"1000\" srcset=\"https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/DSC_0024-1024x1000.jpg 1024w, https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/DSC_0024-300x293.jpg 300w, https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/DSC_0024-768x750.jpg 768w, https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/DSC_0024-1536x1500.jpg 1536w, https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/DSC_0024-2048x2000.jpg 2048w, https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/DSC_0024-750x732.jpg 750w, https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/DSC_0024-1140x1113.jpg 1140w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-1022\" class=\"wp-caption-text\">Conferencia de prensa en UEPC, Villa Mar\u00eda.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Por su parte, Camilo Rodr\u00edguez, dirigente de la comisi\u00f3n de Jubilados y Pensionados Municipales del Interior de C\u00f3rdoba, en conversaci\u00f3n con este medio, reclam\u00f3 que \u201cnosotros tenemos poco margen, hay localidades donde sorprende lo que padecen los jubilados, no nos alcanza para comer, los remedios son car\u00edsimos, es una lucha jodida\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante la tarde de ayer, la Central General de los Trabajadores (CGT) de C\u00f3rdoba realiz\u00f3 una conferencia de prensa en su Casa Hist\u00f3rica, en la calle V\u00e9lez Sarsfield, donde los dirigentes declararon el \u201cestado de conflicto\u201d. Participaron los sindicatos de trabajadores legislativos, judiciales y graficos, el SEP (empleados p\u00fablicos), UEPC (docentes), AMET (Magisterio de Ense\u00f1anza T\u00e9cnica), ADEME (docentes), Luz y Fuerza (EPEC), bancarios, SUOEM (municipales), SADOP (docentes privados), Casinos, APSE (personal superior de EPEC) y SIVIALCO (viales).<\/span><\/p>\n<blockquote class=\"pullquote align-center\"><p><span style=\"font-weight: 400;\">\u201cRepudiamos este nuevo ataque a los trabajadores. Estamos ante la reforma m\u00e1s regresiva desde el inicio de la democracia y volviendo a los 90 previsionalmente hablando. Los estatales y gremios aportantes a la caja, en unidad vamos a enfrentar este nuevo ajuste\u201d. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Federico Cortelletti, Secretario General de AGEPJ.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Ademas, la CGT Rodr\u00edguez Pe\u00f1a, la CTA Regional C\u00f3rdoba y la CTA de los trabajadores emitieron un comunicado en conjunto, denunciando la inconstitucionalidad de la ley, \u201cel atropello a la voluntad popular\u201d y la \u201ccomplicidad\u201d del Gobierno para con \u201clos evasores seriales de la Fundaci\u00f3n Mediterr\u00e1nea y de la Mesa de Enlace Agropecuaria, ajustando haberes previsionales y salarios\u201d.<\/span><\/p>\n<figure id=\"attachment_1017\" aria-describedby=\"caption-attachment-1017\" style=\"width: 766px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1017\" src=\"https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/bf485276-1f30-4bc9-9903-250c953a5ca2-1-766x1024.jpg\" alt=\"\" width=\"766\" height=\"1024\" srcset=\"https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/bf485276-1f30-4bc9-9903-250c953a5ca2-1-766x1024.jpg 766w, https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/bf485276-1f30-4bc9-9903-250c953a5ca2-1-225x300.jpg 225w, https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/bf485276-1f30-4bc9-9903-250c953a5ca2-1-768x1026.jpg 768w, https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/bf485276-1f30-4bc9-9903-250c953a5ca2-1-750x1002.jpg 750w, https:\/\/tribunavm.com.ar\/wp-content\/uploads\/2020\/05\/bf485276-1f30-4bc9-9903-250c953a5ca2-1.jpg 958w\" sizes=\"(max-width: 766px) 100vw, 766px\" \/><figcaption id=\"caption-attachment-1017\" class=\"wp-caption-text\">Comunicado de la CGT y CTA-A de Villa Mar\u00eda<\/figcaption><\/figure>\n<p>https:\/\/www.facebook.com\/ctaaregcba\/posts\/2505226406245104<\/p>\n<\/div>\n<\/div>\n<p>https:\/\/www.facebook.com\/permalink.php?story_fbid=2941161445919654&#038;id=1829148347120975<\/p>\n<p>https:\/\/www.facebook.com\/cgtregionalcba\/posts\/1597013500479858<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rotundo rechazo al proyecto de Ley impulsado por el oficialismo provincial que busca reducir los haberes jubilatorios. Centrales de trabajadores y gremios de toda la provincia denunciaron la medida. Con 46 votos a favor, 12 en contra, 3 abstenciones, y 9 ausentes, el Gobierno de C\u00f3rdoba impuls\u00f3 y aprob\u00f3, en la legislatura provincial un proyecto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"0","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":""},"jnews_primary_category":{"id":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"_joinchat":[],"footnotes":""},"categories":[22],"tags":[72,39,35],"class_list":["post-1013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-edicion-digital","tag-gobierno","tag-trabajadores"],"_links":{"self":[{"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1013"}],"collection":[{"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=1013"}],"version-history":[{"count":7,"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1013\/revisions"}],"predecessor-version":[{"id":1131,"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/1013\/revisions\/1131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/media\/1021"}],"wp:attachment":[{"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=1013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=1013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tribunavm.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=1013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}